{"id":336,"date":"2021-08-31T09:58:53","date_gmt":"2021-08-31T07:58:53","guid":{"rendered":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue"},"modified":"2022-06-02T14:11:52","modified_gmt":"2022-06-02T12:11:52","slug":"cookie-policy-ue","status":"publish","type":"page","link":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue","title":{"rendered":"Cookie Policy (UE)"},"content":{"rendered":"<p>\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Questa politica sui cookie \u00e8 stata aggiornata l&#8217;ultima volta il 2 Giugno 2022 e si applica ai cittadini e ai residenti permanenti legali dello Spazio Economico Europeo e della Svizzera.<\/i><br><\/p><h2>1. Introduzione<\/h2><p>Il nostro sito web, <a href=\"https:\/\/www.ital-web.it\/crameinfissialghero\">https:\/\/www.ital-web.it\/crameinfissialghero<\/a> (di seguito: &#8220;il sito web&#8221;) utilizza i cookie e altre tecnologie correlate (per comodit\u00e0 tutte le tecnologie sono definite &#8220;cookie&#8221;). I cookie vengono anche inseriti da terze parti che abbiamo ingaggiato. Nel documento sottostante ti informiamo sull&#8217;uso dei cookie sul nostro sito web.<\/p><h2>2. Cosa sono i cookie?<\/h2><p>I cookie sono dei semplici file spediti assieme alle pagine di questo sito e salvati dal tuo browser sul disco rigido del tuo computer o altri dispositivi. Le informazioni raccolte in essi possono venire rispediti ai nostri server oppure ai server di terze parti durante la prossima visita.<\/p><h2>3. Cosa sono gli script?<\/h2><p>Uno script \u00e8 un pezzo di codice usato per far funzionare correttamente ed interattivamente il nostro sito. Questo codice viene eseguito sui nostri server o sul tuo dispositivo.<\/p><h2>4. Cos&#039;\u00e8 un web beacon?<\/h2><p>Un web beacon (o pixel tag) \u00e8 un piccolo, invisibile pezzo di testo o immagine su un sito che viene usato per monitorare il traffico di un sito web. Per fare questo, diversi dati su di te vengono conservati utilizzando dei web beacon.<\/p><h2>5. Cookie<\/h2><h3>5.1 Cookie tecnici o funzionali<\/h3><p>Alcuni cookie assicurano il corretto funzionamento del sito e che le tue preferenze rimangano valide. Piazzando cookie funzionali, rendiamo pi\u00f9 facile per te visitare il nostro sito web. In questo modo non devi inserire ripetutamente le stesse informazioni quando visiti il nostro sito web, per esempio, l&#8217;oggetto rimane nel tuo carrello finch\u00e9 non hai pagato. Possiamo piazzare questi cookie senza il tuo consenso.<\/p><h3>5.2 Cookie statistici<\/h3><p>Utilizziamo i cookie statistici per ottimizzare l&#8217;esperienza del sito web per i nostri utenti. Con questi cookie statistici otteniamo approfondimenti sull&#8217;uso del nostro sito web.&nbsp;Chiediamo il tuo permesso per piazzare cookie statistici.<\/p><h3>5.3 Cookie di marketing\/tracciamento<\/h3><p>I cookie di marketing\/tracciamento sono cookie o qualsiasi altra forma di memorizzazione locale, utilizzati per creare profili utente per visualizzare pubblicit\u00e0 o per tracciare l&#8217;utente su questo sito web o su diversi siti web per scopi di marketing simili.<\/p><h2>6. Cookie inseriti<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Funzionale, Pubblicit\u00e0\/Tracciamento<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google reCAPTCHA per prevenzione dello spam. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Read more about Google reCAPTCHA<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/_grecaptcha\/\">_grecaptcha<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce protezione spam<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0\/Tracciamento<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Filtra richieste dei bot<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo WordPress per sviluppo del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Read more about WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_data_user_-2\/\">WP_DATA_USER_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Salvare le preferenze utente<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-api-schema-model-2\/\">wp-api-schema-model*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Controlla se i cookie possono essere piazzati<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Mantieni l&#039;accesso degli utenti<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Divi (Elegant Themes)<\/h3>\n\t\t<p>Funzionale<\/p>\n\t\t<label for=\"cmplz_service_divi-(elegant-themes)\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service divi-(elegant-themes)<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divi-(elegant-themes)\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divi-(elegant-themes)\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Divi (Elegant Themes) per design del sito web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/divi-elegant-themes\/\">Read more about Divi (Elegant Themes)<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Questi dati non sono condivisi con terze parti.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funzionale<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/divi-elegant-themes\/et-pb-recent-items-colors\/\">et-pb-recent-items-colors<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">persistente<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Fornisce funzioni attraverso diverse pagine<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/divi-elegant-themes\/et-editor-available-post\/\">et-editor-available-post-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">sessione<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Pubblicit\u00e0\/Tracciamento<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p>Usiamo Google Fonts per mostrare i webfont. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Read more about Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>Per ulteriori informazioni, si prega di leggere <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Dichiarazione sulla Privacy<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Pubblicit\u00e0\/Tracciamento<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">nessuno<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\">Richiedere l&#8217;indirizzo IP dell&#8217;utente<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varie<\/h3>\n\t\t<p>Scopo in attesa di indagine<\/p>\n\t\t<label for=\"cmplz_service_varie\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varie<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varie\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varie\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilizzo<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Condivisione dei dati<\/h4>\n\t\t<p>La condivisione dei dati \u00e8 in attesa di indagine<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Scopo in attesa di indagine<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">real-queue-restore-jobs-1ec681f2c47a1f0ec01c74799b669ef6<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">etfb-autosave-30<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_choice<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics-anonymous<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consent_status<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_fbp<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_choice<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_statistics-anonymous<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_consent_status<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consenttype<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">lastClipboardTimestamp<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">tablesorter-savesort<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">iberezansky3DFlipBookEdit<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">etfb-autosave-61<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-pb-recent-items-font_family<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_at.cww<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">at-rand<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">at-lojson-cache-ra-584ec0ebef0525db<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_at.hist.0419<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-cloud.viewMode<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">etfb-autosave-62<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">etfb-autosave-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__stripe_mid<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">km_ai<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">km_lv<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__atuvc<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">burst_uid<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_rt_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\">365 giorni<\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-1609-bb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">et-saved-post-3661-bb<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Scadenza<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funzione<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consenso<\/h2><p>Quando visiti il sito web per la prima volta, noi mostreremo un popup con una spiegazione dei cookie. Appena clicchi su &#8220;Salva preferenze&#8221;, dai il permesso a noi di usare le categorie di cookie e plugin come descritto in questa dichiarazione relativa ai popup e cookie. Puoi disabilitare i cookie attraverso il tuo browser, ma prendi in considerazione, che il nostro sito web potrebbe non funzionare pi\u00f9 correttamente.<\/p><h3>7.1 Gestisci le tue impostazioni di consenso<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Hai caricato la Cookie Policy senza supporto javascript.&nbsp;Su AMP, puoi usare il pulsante di gestione del consenso in fondo alla pagina.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Abilitare\/disabilitare e cancellazione dei cookie<\/h2><p>Puoi usare il tuo browser per cancellare automaticamente o manualmente i cookie. \u00c8 anche possibile specificare che determinati cookie non possono essere piazzati. Un&#8217;altra opzione \u00e8 quella di modificare le impostazioni del tuo browser internet in modo da ricevere un messaggio ogni volta che viene inserito un cookie. Per ulteriori informazioni su queste opzioni, consultare le istruzioni nella sezione Guida del tuo browser.<\/p><p>Tieni presente che il nostro sito web potrebbe non funzionare correttamente se tutti i cookie sono disabilitati. Se cancelli i cookie nel vostro browser, essi verranno nuovamente inseriti dopo il consenso fornito quando visiterete nuovamente il nostro sito web.<\/p><h2>9. I tuoi diritti in relazione ai dati personali<\/h2><p>Hai i seguenti diritti relativi ai tuoi dati personali:<\/p><ul>\n                    <li>Hai il diritto di sapere quando i tuoi dati personali sono necessari, cosa succede ad essi, quanto a lungo verranno mantenuti.<\/li>\n                    <li>Diritto di accesso: hai il diritto ad accedere ai tuoi dati personali dei quali siamo a conoscenza.<\/li>\n                    <li>Diritto di rettifica: hai il diritto di completare, correggere, cancellare o bloccare i tuoi dati personali quando lo desideri.<\/li>\n                    <li>Se ci darai il consenso per elaborare i tuoi dati, hai il diritto di revocare questo consenso e di eliminare i tuoi dati personali.<\/li>\n                    <li>Diritto di trasferire i tuoi dati: hai il diritto di richiedere tutti i tuoi dati dal controllore e trasferirli tutti quanti ad un altro controllore.<\/li>\n                    <li>Diritto di opposizione: hai il diritto ad opporti al trattamento dei tuoi dati. Noi rispetteremo questa scelta, a meno che non ci siano delle motivazioni valide per trattarli.<\/li>\n                <\/ul><p>Per esercitare questi diritti, non esitate a contattarci. Si prega di fare riferimento ai dettagli di contatto in fondo a questa Cookie Policy. Se hai un reclamo su come gestiamo i tuoi dati, vorremmo sentirti, ma hai anche il diritto di presentare un reclamo all&#8217;autorit\u00e0 di vigilanza (l&#8217;Autorit\u00e0 per la Protezione dei Dati).<\/p><h2>10. Dettagli di contatto<\/h2><p>Per domande e\/o commenti riguardo la Cookie Policy e questa dichiarazione, per favore contattaci usando i seguenti dati di contatto:<\/p><p><span class=\"cmplz-contact-organisation\">CRAME SRLS<\/span><br>\n                      <span class=\"cmplz-contact-address\">Via Monte D&#8217;Olla,108 &#8211; 07041 ALGHERO (SS)<br \/>\r\n<br \/>\r\n<br \/>\r\n<\/span><br>\n                      <span class=\"cmplz-contact-country\">Italia<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Sito web: <a href=\"https:\/\/www.ital-web.it\/crameinfissialghero\">https:\/\/www.ital-web.it\/crameinfissialghero<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Email: <span class=\"cmplz-obfuscate\">&#099;&#114;&#097;me&#046;i&#110;s&#116;&#097;&#108;lazi&#111;ni@<span class=\"cmplz-fmail-domain\">ex.co&#109;<\/span>l&#105;b&#101;ro&#046;i&#116;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Numero di telefono: 079 4123058<\/span><\/p><p>Questa politica sui cookie \u00e8 stata sincronizzata con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> il 31 Agosto 2021.<\/p><\/div><\/p>\r\n<h4><strong>Ulteriori informazioni e link utili<\/strong><\/h4>\r\n<p><strong><em>Cookie gestiti da terze parti<\/em><\/strong><\/p>\r\n<p><em>Troverai di seguito alcune indicazioni, e un link alla privacy policy e al modulo di consenso di e\u00a0 il nome dei terzi che li gestiscono, e per ciascuno di essi il link alla pagina nella quale potrai ricevere le informazioni sul trattamento e esprimere il tuo consenso.<\/em><\/p>\r\n<p><em>\u2013 Cookie di social network vengono utilizzati per la condivisione di contenuti sui social network<\/em><\/p>\r\n<p><em>YOU TUBE:\u00a0<\/em><a href=\"http:\/\/www.google.it\/intl\/it\/policies\/privacy\/\"><em>http:\/\/www.google.it\/intl\/it\/policies\/privacy\/<\/em><\/a><\/p>\r\n<p><em>FACEBOOK:\u00a0<\/em><a href=\"http:\/\/developers.facebook.com\/\"><em>http:\/\/developers.facebook.com\/<\/em><\/a><\/p>\r\n<p><em>TWITTER:\u00a0<\/em><a href=\"https:\/\/twitter.com\/it\/privacy\"><em>https:\/\/twitter.com\/it\/privacy<\/em><\/a><em>\u00a0<\/em><\/p>\r\n<p><em>\u2013 Cookie di statistica: Vengono usati cookie di statistica di terza parte (Google Analytics), per la gestione di statistiche in forma anonima, senza tracciamento dell\u2019IP dell\u2019Utente (dati utente non profilati a livello di IP), con condivisione dei dati con la Terza Parte.<\/em><\/p>\r\n<p><strong><em>Accesso alle informazioni della Terza Parte:<\/em><\/strong><\/p>\r\n<p><em>Privacy Policy:\u00a0<\/em><a href=\"http:\/\/www.google.com\/policies\/privacy\/\"><em>http:\/\/www.google.com\/policies\/privacy\/<\/em><\/a><\/p>\r\n<p><em>Cookie Policy:\u00a0<\/em><a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage\"><em>https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage<\/em><\/a><\/p>\r\n<p><a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage\"><em>https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage<\/em><\/a><\/p>\r\n<p><em>Per la disattivazione:\u00a0<\/em><a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it\"><em>https:\/\/tools.google.com\/dlpage\/gaoptout?hl=it<\/em><\/a><\/p>\r\n<p><em>Altre tecnologie (es. plugin, widget, local storage, etc)<\/em><\/p>\r\n<p><strong><em>Interazione con social network e piattaforme esterne<\/em><\/strong><\/p>\r\n<p><em>Widget: \u00e8 un componente grafico di interfaccia utente di un programma, che ha lo scopo di facilitare all\u2019utente l\u2019interazione con il programma stesso. I widget maggiormente utilizzati sono quelli dei social network, che permettono agli utenti di aprire in modo agevole del browser i social network in una finestra separata.<\/em><\/p>\r\n<p><em>Questi servizi permettono di effettuare interazioni con i social network o con altre piattaforme esterne, direttamente dalle pagine di un sito. Le interazioni e le informazioni eventualmente acquisite dal sito sono soggette alle impostazioni privacy del terzo che ha creato le tecnologie suddette. Per ricevere informazioni dettagliate in merito all\u2019utilizzo dei dati personali trattati quando usufruisci di queste tecnologie, ti invitiamo a visitare i siti internet dei terzi gestori delle suddette tecnologie.Troverai di seguito i riferimenti di tali terzi, ed accanto a ciascuna di esse troverai il link alla pagina nella quale potrai ricevere le informazioni sul trattamento e, ove previsto dalla normativa, esprimere o negare il tuo consenso:<\/em><\/p>\r\n<p><em>-Widget social di Facebook\u00a0<\/em><a href=\"https:\/\/www.facebook.com\/privacy\/explanation\"><em>https:\/\/www.facebook.com\/privacy\/explanation<\/em><\/a><\/p>\r\n<p><em>-Widget social di Twitter\u00a0<\/em><a href=\"https:\/\/twitter.com\/privacy?lang=it\"><em>https:\/\/twitter.com\/privacy?lang=it<\/em><\/a><em>\u00a0<\/em><\/p>\r\n<p><em>-Widget social Youtube (Google)\u00a0<\/em><a href=\"http:\/\/www.google.com\/intl\/it\/policies\/privacy\/\"><em>http:\/\/www.google.com\/intl\/it\/policies\/privacy\/<\/em><\/a><em>\u00a0\u00a0<\/em><\/p>\r\n<p><em>-Widget social Linkedin (Linkedin)\u00a0<\/em><a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\"><em>https:\/\/www.linkedin.com\/legal\/privacy-policy<\/em><\/a><\/p>\r\n<p><em>Ricordati che puoi gestire le tue preferenze sui cookie anche attraverso il browser<\/em><\/p>\r\n<p><em>Se non conosci il tipo e la versione di browser che stai utilizzando, clicca su \u201cAiuto\u201d nella finestra del browser in alto, per accedere a tutte le informazioni necessarie.<\/em><\/p>\r\n<p><em>Se invece conosci il tuo browser, clicca su quello che stai utilizzando per accedere alla pagina di gestione dei cookie.<\/em><\/p>\r\n<p><em>Internet Explorer\u00a0<\/em><a href=\"http:\/\/windows.microsoft.com\/en-us\/windows-vista\/block-or-allow-cookies\"><em>http:\/\/windows.microsoft.com\/en-us\/windows-vista\/block-or-allow-cookies<\/em><\/a><\/p>\r\n<p><em>Google Chrome\u00a0<\/em><a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=it\"><em>https:\/\/support.google.com\/accounts\/answer\/61416?hl=it<\/em><\/a><\/p>\r\n<p><em>Mozilla Firefox\u00a0<\/em><a href=\"http:\/\/support.mozilla.org\/en-US\/kb\/Enabling%20and%20disabling%20cookies\"><em>http:\/\/support.mozilla.org\/en-US\/kb\/Enabling%20and%20disabling%20cookies<\/em><\/a><\/p>\r\n<p><em>Safari\u00a0<\/em><a href=\"http:\/\/www.apple.com\/legal\/privacy\/\"><em>http:\/\/www.apple.com\/legal\/privacy\/<\/em><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ulteriori informazioni e link utili Cookie gestiti da terze parti Troverai di seguito alcune indicazioni, e un link alla privacy policy e al modulo di consenso di e\u00a0 il nome dei terzi che li gestiscono, e per ciascuno di essi il link alla pagina nella quale potrai ricevere le informazioni sul trattamento e esprimere il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-336","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls\" \/>\n<meta property=\"og:description\" content=\"Ulteriori informazioni e link utili Cookie gestiti da terze parti Troverai di seguito alcune indicazioni, e un link alla privacy policy e al modulo di consenso di e\u00a0 il nome dei terzi che li gestiscono, e per ciascuno di essi il link alla pagina nella quale potrai ricevere le informazioni sul trattamento e esprimere il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue\" \/>\n<meta property=\"og:site_name\" content=\"Infissi alluminio Alghero - CRAME Srls\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-02T12:11:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/cookie-policy-ue\",\"url\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/cookie-policy-ue\",\"name\":\"Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#website\"},\"datePublished\":\"2021-08-31T07:58:53+00:00\",\"dateModified\":\"2022-06-02T12:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/cookie-policy-ue#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/cookie-policy-ue\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/cookie-policy-ue#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie Policy (UE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#website\",\"url\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/\",\"name\":\"Infissi alluminio Alghero - CRAME Srls\",\"description\":\"Produzione infissi per edifici privati e pubblici\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#organization\",\"name\":\"CRAME Srls Produzione infissi\",\"url\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CRAME Srls Produzione infissi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ital-web.it\\\/crameinfissialghero\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue","og_locale":"it_IT","og_type":"article","og_title":"Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls","og_description":"Ulteriori informazioni e link utili Cookie gestiti da terze parti Troverai di seguito alcune indicazioni, e un link alla privacy policy e al modulo di consenso di e\u00a0 il nome dei terzi che li gestiscono, e per ciascuno di essi il link alla pagina nella quale potrai ricevere le informazioni sul trattamento e esprimere il [&hellip;]","og_url":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue","og_site_name":"Infissi alluminio Alghero - CRAME Srls","article_modified_time":"2022-06-02T12:11:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue","url":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue","name":"Cookie Policy (UE) - Infissi alluminio Alghero - CRAME Srls","isPartOf":{"@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#website"},"datePublished":"2021-08-31T07:58:53+00:00","dateModified":"2022-06-02T12:11:52+00:00","breadcrumb":{"@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/cookie-policy-ue#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ital-web.it\/crameinfissialghero\/"},{"@type":"ListItem","position":2,"name":"Cookie Policy (UE)"}]},{"@type":"WebSite","@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#website","url":"https:\/\/www.ital-web.it\/crameinfissialghero\/","name":"Infissi alluminio Alghero - CRAME Srls","description":"Produzione infissi per edifici privati e pubblici","publisher":{"@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ital-web.it\/crameinfissialghero\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#organization","name":"CRAME Srls Produzione infissi","url":"https:\/\/www.ital-web.it\/crameinfissialghero\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CRAME Srls Produzione infissi"},"image":{"@id":"https:\/\/www.ital-web.it\/crameinfissialghero\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/pages\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":0,"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/pages\/336\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ital-web.it\/crameinfissialghero\/wp-json\/wp\/v2\/media?parent=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}